{"id":47,"date":"2011-12-21T18:42:22","date_gmt":"2011-12-21T17:42:22","guid":{"rendered":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/?p=47"},"modified":"2011-12-21T18:42:22","modified_gmt":"2011-12-21T17:42:22","slug":"die-dividende-der-revolution","status":"publish","type":"post","link":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/2011\/12\/21\/die-dividende-der-revolution\/","title":{"rendered":"Die Dividende der Revolution"},"content":{"rendered":"<p>Vor vielen Jahren erkl\u00e4rte mir ein \u00e4gyptischer Unternehmer: &#8222;Nirgendwo auf dieser Welt gibt es so viele Gener\u00e4le wie in \u00c4gypten.&#8220; Ich war schon einigerma\u00dfen verbl\u00fcfft. Doch er verdeutlichte es mir ziemlich einfach: &#8222;Jeder Soldat, der entlassen wird, rechnet im Zivilleben anschlie\u00dfend nach, welchen Rang er erreicht h\u00e4tte, wenn er jetzt noch beim Milit\u00e4r w\u00e4re. Irgendwann mal sind dann alle Gener\u00e4le.&#8220;<\/p>\n<p>Inzwischen hat sich das wohl ein wenig ge\u00e4ndert. Tatsache ist aber, dass das Milit\u00e4r bis vor einem Jahr sehr beliebt war, obwohl es seit fast 60 Jahren einen Staat im Staat darstellt. Das d\u00fcrfte daran liegen, dass es die &#8222;Gruppe der freien Offiziere&#8220; war, die 1952 den korrupten K\u00f6nik Faruk zum Teufel jagte. Auch das war damals eine Revolution. Eine der wichtigen Errungenschaften dieser Revolution war das Frauenwahlrecht. (In diesem Zusammenhang dr\u00e4ngt sich mir eine ganz aktuelle Frage auf: Jehan al-Sadat schreibt in ihrer Autobiographie &#8222;Ich bin eine Frau aus \u00c4gypten&#8220;, dass es 1976 in \u00c4gypten f\u00fcr die M\u00e4nner Wahlpflicht und f\u00fcr Frauen das Wahlrecht gab. Wie sieht das 2011 aus?)<\/p>\n<p>Tats\u00e4chlich geh\u00f6rten Frauen zu den gro\u00dfen Gewinnerinnen der Revolution von 1952. Da mutet es schon sehr bedr\u00fcckend an, dass es in diesen Tagen ausgerechnet Frauen sind, die sich vom \u00e4gyptischen Milit\u00e4r \u00fcber den Tahrir jagen lassen m\u00fcssen, die verpr\u00fcgelt und denen die Kleider vom Leib gerissen werden. Auf der anderen Seite f\u00e4llt auf, dass offenbar ein machtvolles Wort der US-Au\u00dfenministerin(!) gen\u00fcgt, und die Gener\u00e4le knicken ein. Damit will ich nat\u00fcrlich nicht den Marsch der Frauen am Dienstagabend unterbewerten. Aber die lautstarke Solidarisierung von Hillary Clinton wird schon ihren Teil zu der \u00fcberraschenden Entschuldigung des Milit\u00e4rrats beigetragen haben.<\/p>\n<p>Trotzdem, es gibt in \u00c4gypten durchaus auch Leute, die dieses Horrorbild von der verpr\u00fcgelten Demonstrantin ganz anders bewerten, als der Rest der Welt. Eine brave, fromme \u00c4gypterin w\u00fcrde niemals einen blauen BH tragen, und deshalb k\u00f6nne diese Frau nur eine Prostituierte sein. Hm, als ich das geh\u00f6rt habe, fiel mir ein, dass angeblich Frauen schwerreicher Saudis regelm\u00e4\u00dfig tief verschleiert Pariser Dessous-Gesch\u00e4fte leer kaufen. Das Geld, das dann noch \u00fcbrig bleibt, spenden ihre M\u00e4nner dann vermutlich an die \u00e4gyptischen Salafisten.<\/p>\n<p>Doch ernsthaft: Es waren vor einem Jahr auch unz\u00e4hlige Frauen, die auf dem Tahrir daf\u00fcr sorgten, dass das Mubarak-Regime gest\u00fcrzt wurde. Ausgerechnet sie sollen nach der Revolution weniger Rechte haben, als zuvor? Sogar die Frauenquote, noch von Mubarak eingef\u00fchrt, auf den Kandidatenlisten zur Wahl ist schon gekippt worden. Aus europ\u00e4ischer Sicht verl\u00e4uft die Bruchlinie im \u00c4gypten nach der Revolution zwischen S\u00e4kularen und Islamisten. Vielleicht verl\u00e4uft sie seit gestern auch zwischen M\u00e4nnern und Frauen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vor vielen Jahren erkl\u00e4rte mir ein \u00e4gyptischer Unternehmer: &#8222;Nirgendwo auf dieser Welt gibt es so viele Gener\u00e4le wie in \u00c4gypten.&#8220; Ich war schon einigerma\u00dfen verbl\u00fcfft. Doch er verdeutlichte es mir ziemlich einfach: &#8222;Jeder Soldat, der entlassen wird, rechnet im Zivilleben &hellip; <a href=\"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/2011\/12\/21\/die-dividende-der-revolution\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,20,38,39,102,103,106,148,155,166,178,241,263,266,306],"class_list":["post-47","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-agypten","tag-agyptisches-militar","tag-arabellion","tag-arabische-revolution","tag-frauenwahlrecht","tag-freie-offiziere","tag-fremdenverkehr","tag-hillary-clinton","tag-hurghada","tag-jahan-al-sadat","tag-konig-faruk","tag-peter-s-kaspar","tag-rotes-meer","tag-salafisten","tag-tourismus"],"wp-worthy-pixel":{"ignored":false,"public":"376901ca1bd7449581942cf51acdc06c","server":"vg04.met.vgwort.de","url":"https:\/\/vg04.met.vgwort.de\/na\/376901ca1bd7449581942cf51acdc06c"},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/posts\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/comments?post=47"}],"version-history":[{"count":0,"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/posts\/47\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/media?parent=47"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/categories?post=47"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carpathia-verlag.de\/koulou-tamam\/wp-json\/wp\/v2\/tags?post=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}